{"id":104,"count":4,"description":"","link":"https:\/\/montessori-seeds.ch\/en\/adolescents\/","name":"Adolescents","slug":"adolescents","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/montessori-seeds.ch\/en\/wp-json\/wp\/v2\/categories\/104","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/montessori-seeds.ch\/en\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/montessori-seeds.ch\/en\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/montessori-seeds.ch\/en\/wp-json\/wp\/v2\/posts?categories=104"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}